{"id":25143,"date":"2023-09-28T09:02:58","date_gmt":"2023-09-28T08:02:58","guid":{"rendered":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2023\/09\/FLORIUM_MILLENIUM_75_LMF_01-e1689698535920-1024x660-1.jpg"},"modified":"2023-09-28T09:02:58","modified_gmt":"2023-09-28T08:02:58","slug":"florium_millenium_75_lmf_01-e1689698535920-1024x660-2","status":"inherit","type":"attachment","link":"https:\/\/www.fleurette-florium.fr\/nl\/florium_millenium_75_lmf_01-e1689698535920-1024x660-2\/","title":{"rendered":"FLORIUM_MILLENIUM_75_LMF_01-e1689698535920-1024&#215;660"},"author":8791,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"media_folder":[],"class_list":["post-25143","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>FLORIUM_MILLENIUM_75_LMF_01-e1689698535920-1024x660 - Fleurette Florium<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2023\/09\/FLORIUM_MILLENIUM_75_LMF_01-e1689698535920-1024x660-1.jpg\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FLORIUM_MILLENIUM_75_LMF_01-e1689698535920-1024x660 - Fleurette Florium\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2023\/09\/FLORIUM_MILLENIUM_75_LMF_01-e1689698535920-1024x660-1.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Fleurette Florium\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2023\/09\/FLORIUM_MILLENIUM_75_LMF_01-e1689698535920-1024x660-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"660\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/FLORIUM_MILLENIUM_75_LMF_01-e1689698535920-1024x660-1.jpg\",\"url\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/FLORIUM_MILLENIUM_75_LMF_01-e1689698535920-1024x660-1.jpg\",\"name\":\"FLORIUM_MILLENIUM_75_LMF_01-e1689698535920-1024x660 - Fleurette Florium\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/#website\"},\"datePublished\":\"2023-09-28T08:02:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/FLORIUM_MILLENIUM_75_LMF_01-e1689698535920-1024x660-1.jpg#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fleurette-florium.fr\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/FLORIUM_MILLENIUM_75_LMF_01-e1689698535920-1024x660-1.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/FLORIUM_MILLENIUM_75_LMF_01-e1689698535920-1024x660-1.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\",\"item\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/nl\\\/home-florium\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FLORIUM_MILLENIUM_75_LMF_01-e1689698535920-1024&#215;660\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/#website\",\"url\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/\",\"name\":\"Fleurette Florium\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/#organization\",\"name\":\"Fleurette Florium\",\"url\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/logo-fleurette-florium-scaled.png\",\"contentUrl\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/logo-fleurette-florium-scaled.png\",\"width\":2560,\"height\":830,\"caption\":\"Fleurette Florium\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FLORIUM_MILLENIUM_75_LMF_01-e1689698535920-1024x660 - Fleurette Florium","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2023\/09\/FLORIUM_MILLENIUM_75_LMF_01-e1689698535920-1024x660-1.jpg","og_locale":"nl_NL","og_type":"article","og_title":"FLORIUM_MILLENIUM_75_LMF_01-e1689698535920-1024x660 - Fleurette Florium","og_url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2023\/09\/FLORIUM_MILLENIUM_75_LMF_01-e1689698535920-1024x660-1.jpg","og_site_name":"Fleurette Florium","og_image":[{"width":1024,"height":660,"url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2023\/09\/FLORIUM_MILLENIUM_75_LMF_01-e1689698535920-1024x660-1.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2023\/09\/FLORIUM_MILLENIUM_75_LMF_01-e1689698535920-1024x660-1.jpg","url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2023\/09\/FLORIUM_MILLENIUM_75_LMF_01-e1689698535920-1024x660-1.jpg","name":"FLORIUM_MILLENIUM_75_LMF_01-e1689698535920-1024x660 - Fleurette Florium","isPartOf":{"@id":"https:\/\/www.fleurette-florium.fr\/#website"},"datePublished":"2023-09-28T08:02:58+00:00","breadcrumb":{"@id":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2023\/09\/FLORIUM_MILLENIUM_75_LMF_01-e1689698535920-1024x660-1.jpg#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2023\/09\/FLORIUM_MILLENIUM_75_LMF_01-e1689698535920-1024x660-1.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2023\/09\/FLORIUM_MILLENIUM_75_LMF_01-e1689698535920-1024x660-1.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"","item":"https:\/\/www.fleurette-florium.fr\/nl\/home-florium\/"},{"@type":"ListItem","position":2,"name":"FLORIUM_MILLENIUM_75_LMF_01-e1689698535920-1024&#215;660"}]},{"@type":"WebSite","@id":"https:\/\/www.fleurette-florium.fr\/#website","url":"https:\/\/www.fleurette-florium.fr\/","name":"Fleurette Florium","description":"","publisher":{"@id":"https:\/\/www.fleurette-florium.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fleurette-florium.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/www.fleurette-florium.fr\/#organization","name":"Fleurette Florium","url":"https:\/\/www.fleurette-florium.fr\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/www.fleurette-florium.fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2021\/07\/logo-fleurette-florium-scaled.png","contentUrl":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2021\/07\/logo-fleurette-florium-scaled.png","width":2560,"height":830,"caption":"Fleurette Florium"},"image":{"@id":"https:\/\/www.fleurette-florium.fr\/#\/schema\/logo\/image\/"}}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2023\/09\/FLORIUM_MILLENIUM_75_LMF_01-e1689698535920-1024x660-1.jpg'><img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"193\" src=\"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2023\/09\/FLORIUM_MILLENIUM_75_LMF_01-e1689698535920-1024x660-1-300x193.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2023\/09\/FLORIUM_MILLENIUM_75_LMF_01-e1689698535920-1024x660-1-300x193.jpg 300w, https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2023\/09\/FLORIUM_MILLENIUM_75_LMF_01-e1689698535920-1024x660-1-768x495.jpg 768w, https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2023\/09\/FLORIUM_MILLENIUM_75_LMF_01-e1689698535920-1024x660-1.jpg 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1024,"height":660,"file":"2023\/09\/FLORIUM_MILLENIUM_75_LMF_01-e1689698535920-1024x660-1.jpg","filesize":163422,"sizes":{"medium":{"file":"FLORIUM_MILLENIUM_75_LMF_01-e1689698535920-1024x660-1-300x193.jpg","width":300,"height":193,"filesize":20012,"mime_type":"image\/jpeg","source_url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2023\/09\/FLORIUM_MILLENIUM_75_LMF_01-e1689698535920-1024x660-1-300x193.jpg"},"thumbnail":{"file":"FLORIUM_MILLENIUM_75_LMF_01-e1689698535920-1024x660-1-150x150.jpg","width":150,"height":150,"filesize":10112,"mime_type":"image\/jpeg","source_url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2023\/09\/FLORIUM_MILLENIUM_75_LMF_01-e1689698535920-1024x660-1-150x150.jpg"},"medium_large":{"file":"FLORIUM_MILLENIUM_75_LMF_01-e1689698535920-1024x660-1-768x495.jpg","width":768,"height":495,"filesize":92252,"mime_type":"image\/jpeg","source_url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2023\/09\/FLORIUM_MILLENIUM_75_LMF_01-e1689698535920-1024x660-1-768x495.jpg"},"tp-image-grid":{"file":"FLORIUM_MILLENIUM_75_LMF_01-e1689698535920-1024x660-1-700x660.jpg","width":700,"height":660,"filesize":111033,"mime_type":"image\/jpeg","source_url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2023\/09\/FLORIUM_MILLENIUM_75_LMF_01-e1689698535920-1024x660-1-700x660.jpg"},"cmplz_banner_image":{"file":"FLORIUM_MILLENIUM_75_LMF_01-e1689698535920-1024x660-1-350x100.jpg","width":350,"height":100,"filesize":12076,"mime_type":"image\/jpeg","source_url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2023\/09\/FLORIUM_MILLENIUM_75_LMF_01-e1689698535920-1024x660-1-350x100.jpg"},"full":{"file":"FLORIUM_MILLENIUM_75_LMF_01-e1689698535920-1024x660-1.jpg","width":1024,"height":660,"mime_type":"image\/jpeg","source_url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2023\/09\/FLORIUM_MILLENIUM_75_LMF_01-e1689698535920-1024x660-1.jpg"}},"image_meta":{"aperture":"1.5","credit":"","camera":"iPhone 13 Pro Max","caption":"","created_timestamp":"1688555345","copyright":"","focal_length":"5.7","iso":"50","shutter_speed":"0.00017001020061204","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2023\/09\/FLORIUM_MILLENIUM_75_LMF_01-e1689698535920-1024x660-1.jpg","_links":{"self":[{"href":"https:\/\/www.fleurette-florium.fr\/nl\/wp-json\/wp\/v2\/media\/25143","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fleurette-florium.fr\/nl\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.fleurette-florium.fr\/nl\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.fleurette-florium.fr\/nl\/wp-json\/wp\/v2\/users\/8791"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fleurette-florium.fr\/nl\/wp-json\/wp\/v2\/comments?post=25143"}],"wp:term":[{"taxonomy":"media_folder","embeddable":true,"href":"https:\/\/www.fleurette-florium.fr\/nl\/wp-json\/wp\/v2\/media_folder?post=25143"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}