{"id":23701,"date":"2023-04-14T13:53:25","date_gmt":"2023-04-14T12:53:25","guid":{"rendered":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2023\/04\/MAGISTER-74LMG-EXT-11.jpg"},"modified":"2023-04-14T13:53:25","modified_gmt":"2023-04-14T12:53:25","slug":"magister-74lmg-ext-11-2","status":"inherit","type":"attachment","link":"https:\/\/www.fleurette-florium.fr\/nl\/magister-74lmg-ext-11-2\/","title":{"rendered":"MAGISTER-74LMG-EXT-11"},"author":8791,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"media_folder":[],"class_list":["post-23701","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MAGISTER-74LMG-EXT-11 - Fleurette Florium<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2023\/04\/MAGISTER-74LMG-EXT-11-scaled.jpg\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MAGISTER-74LMG-EXT-11 - Fleurette Florium\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2023\/04\/MAGISTER-74LMG-EXT-11-scaled.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Fleurette Florium\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2023\/04\/MAGISTER-74LMG-EXT-11-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/MAGISTER-74LMG-EXT-11-scaled.jpg\",\"url\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/MAGISTER-74LMG-EXT-11-scaled.jpg\",\"name\":\"MAGISTER-74LMG-EXT-11 - Fleurette Florium\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/#website\"},\"datePublished\":\"2023-04-14T12:53:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/MAGISTER-74LMG-EXT-11-scaled.jpg#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fleurette-florium.fr\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/MAGISTER-74LMG-EXT-11-scaled.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/MAGISTER-74LMG-EXT-11-scaled.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\",\"item\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/nl\\\/home-florium\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MAGISTER-74LMG-EXT-11\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/#website\",\"url\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/\",\"name\":\"Fleurette Florium\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/#organization\",\"name\":\"Fleurette Florium\",\"url\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/logo-fleurette-florium-scaled.png\",\"contentUrl\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/logo-fleurette-florium-scaled.png\",\"width\":2560,\"height\":830,\"caption\":\"Fleurette Florium\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MAGISTER-74LMG-EXT-11 - Fleurette Florium","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2023\/04\/MAGISTER-74LMG-EXT-11-scaled.jpg","og_locale":"nl_NL","og_type":"article","og_title":"MAGISTER-74LMG-EXT-11 - Fleurette Florium","og_url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2023\/04\/MAGISTER-74LMG-EXT-11-scaled.jpg","og_site_name":"Fleurette Florium","og_image":[{"width":2560,"height":1920,"url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2023\/04\/MAGISTER-74LMG-EXT-11-scaled.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2023\/04\/MAGISTER-74LMG-EXT-11-scaled.jpg","url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2023\/04\/MAGISTER-74LMG-EXT-11-scaled.jpg","name":"MAGISTER-74LMG-EXT-11 - Fleurette Florium","isPartOf":{"@id":"https:\/\/www.fleurette-florium.fr\/#website"},"datePublished":"2023-04-14T12:53:25+00:00","breadcrumb":{"@id":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2023\/04\/MAGISTER-74LMG-EXT-11-scaled.jpg#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2023\/04\/MAGISTER-74LMG-EXT-11-scaled.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2023\/04\/MAGISTER-74LMG-EXT-11-scaled.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"","item":"https:\/\/www.fleurette-florium.fr\/nl\/home-florium\/"},{"@type":"ListItem","position":2,"name":"MAGISTER-74LMG-EXT-11"}]},{"@type":"WebSite","@id":"https:\/\/www.fleurette-florium.fr\/#website","url":"https:\/\/www.fleurette-florium.fr\/","name":"Fleurette Florium","description":"","publisher":{"@id":"https:\/\/www.fleurette-florium.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fleurette-florium.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/www.fleurette-florium.fr\/#organization","name":"Fleurette Florium","url":"https:\/\/www.fleurette-florium.fr\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/www.fleurette-florium.fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2021\/07\/logo-fleurette-florium-scaled.png","contentUrl":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2021\/07\/logo-fleurette-florium-scaled.png","width":2560,"height":830,"caption":"Fleurette Florium"},"image":{"@id":"https:\/\/www.fleurette-florium.fr\/#\/schema\/logo\/image\/"}}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2023\/04\/MAGISTER-74LMG-EXT-11-scaled.jpg'><img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2023\/04\/MAGISTER-74LMG-EXT-11-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2023\/04\/MAGISTER-74LMG-EXT-11-300x225.jpg 300w, https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2023\/04\/MAGISTER-74LMG-EXT-11-1024x768.jpg 1024w, https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2023\/04\/MAGISTER-74LMG-EXT-11-768x576.jpg 768w, https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2023\/04\/MAGISTER-74LMG-EXT-11-1536x1152.jpg 1536w, https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2023\/04\/MAGISTER-74LMG-EXT-11-2048x1536.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2560,"height":1920,"file":"2023\/04\/MAGISTER-74LMG-EXT-11-scaled.jpg","filesize":247228,"sizes":{"medium":{"file":"MAGISTER-74LMG-EXT-11-300x225.jpg","width":300,"height":225,"filesize":13039,"mime_type":"image\/jpeg","source_url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2023\/04\/MAGISTER-74LMG-EXT-11-300x225.jpg"},"large":{"file":"MAGISTER-74LMG-EXT-11-1024x768.jpg","width":1024,"height":768,"filesize":62811,"mime_type":"image\/jpeg","source_url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2023\/04\/MAGISTER-74LMG-EXT-11-1024x768.jpg"},"thumbnail":{"file":"MAGISTER-74LMG-EXT-11-150x150.jpg","width":150,"height":150,"filesize":8496,"mime_type":"image\/jpeg","source_url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2023\/04\/MAGISTER-74LMG-EXT-11-150x150.jpg"},"medium_large":{"file":"MAGISTER-74LMG-EXT-11-768x576.jpg","width":768,"height":576,"filesize":41262,"mime_type":"image\/jpeg","source_url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2023\/04\/MAGISTER-74LMG-EXT-11-768x576.jpg"},"1536x1536":{"file":"MAGISTER-74LMG-EXT-11-1536x1152.jpg","width":1536,"height":1152,"filesize":114553,"mime_type":"image\/jpeg","source_url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2023\/04\/MAGISTER-74LMG-EXT-11-1536x1152.jpg"},"2048x2048":{"file":"MAGISTER-74LMG-EXT-11-2048x1536.jpg","width":2048,"height":1536,"filesize":176003,"mime_type":"image\/jpeg","source_url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2023\/04\/MAGISTER-74LMG-EXT-11-2048x1536.jpg"},"tp-image-grid":{"file":"MAGISTER-74LMG-EXT-11-700x700.jpg","width":700,"height":700,"filesize":48614,"mime_type":"image\/jpeg","source_url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2023\/04\/MAGISTER-74LMG-EXT-11-700x700.jpg"},"cmplz_banner_image":{"file":"MAGISTER-74LMG-EXT-11-350x100.jpg","width":350,"height":100,"filesize":11223,"mime_type":"image\/jpeg","source_url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2023\/04\/MAGISTER-74LMG-EXT-11-350x100.jpg"},"full":{"file":"MAGISTER-74LMG-EXT-11-scaled.jpg","width":2560,"height":1920,"mime_type":"image\/jpeg","source_url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2023\/04\/MAGISTER-74LMG-EXT-11-scaled.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"original_image":"MAGISTER-74LMG-EXT-11.jpg"},"post":null,"source_url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2023\/04\/MAGISTER-74LMG-EXT-11-scaled.jpg","_links":{"self":[{"href":"https:\/\/www.fleurette-florium.fr\/nl\/wp-json\/wp\/v2\/media\/23701","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fleurette-florium.fr\/nl\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.fleurette-florium.fr\/nl\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.fleurette-florium.fr\/nl\/wp-json\/wp\/v2\/users\/8791"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fleurette-florium.fr\/nl\/wp-json\/wp\/v2\/comments?post=23701"}],"wp:term":[{"taxonomy":"media_folder","embeddable":true,"href":"https:\/\/www.fleurette-florium.fr\/nl\/wp-json\/wp\/v2\/media_folder?post=23701"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}