{"id":21864,"date":"2022-08-24T16:50:34","date_gmt":"2022-08-24T15:50:34","guid":{"rendered":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2022\/08\/implantation-jour-florium-mayflower70LD-de.png"},"modified":"2023-12-05T10:50:28","modified_gmt":"2023-12-05T09:50:28","slug":"implantation-jour-florium-mayflower70ld-de-2","status":"inherit","type":"attachment","link":"https:\/\/www.fleurette-florium.fr\/nl\/gamma-mayflower-camper\/implantation-jour-florium-mayflower70ld-de-2\/","title":{"rendered":"implantation-jour-florium-mayflower70LD-de"},"author":6685,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"media_folder":[],"class_list":["post-21864","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>implantation-jour-florium-mayflower70LD-de - Fleurette Florium<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2022\/08\/implantation-jour-florium-mayflower70LD-de.png\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"implantation-jour-florium-mayflower70LD-de - Fleurette Florium\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2022\/08\/implantation-jour-florium-mayflower70LD-de.png\" \/>\n<meta property=\"og:site_name\" content=\"Fleurette Florium\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-05T09:50:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2022\/08\/implantation-jour-florium-mayflower70LD-de.png\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/implantation-jour-florium-mayflower70LD-de.png\",\"url\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/implantation-jour-florium-mayflower70LD-de.png\",\"name\":\"implantation-jour-florium-mayflower70LD-de - Fleurette Florium\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/#website\"},\"datePublished\":\"2022-08-24T15:50:34+00:00\",\"dateModified\":\"2023-12-05T09:50:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/implantation-jour-florium-mayflower70LD-de.png#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fleurette-florium.fr\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/implantation-jour-florium-mayflower70LD-de.png\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/implantation-jour-florium-mayflower70LD-de.png#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\",\"item\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/nl\\\/home-florium\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gamma Mayflower &#8211; camper met een paviljoenbed\",\"item\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/nl\\\/gamma-mayflower-camper\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"implantation-jour-florium-mayflower70LD-de\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/#website\",\"url\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/\",\"name\":\"Fleurette Florium\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/#organization\",\"name\":\"Fleurette Florium\",\"url\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/logo-fleurette-florium-scaled.png\",\"contentUrl\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/logo-fleurette-florium-scaled.png\",\"width\":2560,\"height\":830,\"caption\":\"Fleurette Florium\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"implantation-jour-florium-mayflower70LD-de - Fleurette Florium","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2022\/08\/implantation-jour-florium-mayflower70LD-de.png","og_locale":"nl_NL","og_type":"article","og_title":"implantation-jour-florium-mayflower70LD-de - Fleurette Florium","og_url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2022\/08\/implantation-jour-florium-mayflower70LD-de.png","og_site_name":"Fleurette Florium","article_modified_time":"2023-12-05T09:50:28+00:00","og_image":[{"width":900,"height":900,"url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2022\/08\/implantation-jour-florium-mayflower70LD-de.png","type":"image\/png"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2022\/08\/implantation-jour-florium-mayflower70LD-de.png","url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2022\/08\/implantation-jour-florium-mayflower70LD-de.png","name":"implantation-jour-florium-mayflower70LD-de - Fleurette Florium","isPartOf":{"@id":"https:\/\/www.fleurette-florium.fr\/#website"},"datePublished":"2022-08-24T15:50:34+00:00","dateModified":"2023-12-05T09:50:28+00:00","breadcrumb":{"@id":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2022\/08\/implantation-jour-florium-mayflower70LD-de.png#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2022\/08\/implantation-jour-florium-mayflower70LD-de.png"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2022\/08\/implantation-jour-florium-mayflower70LD-de.png#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"","item":"https:\/\/www.fleurette-florium.fr\/nl\/home-florium\/"},{"@type":"ListItem","position":2,"name":"Gamma Mayflower &#8211; camper met een paviljoenbed","item":"https:\/\/www.fleurette-florium.fr\/nl\/gamma-mayflower-camper\/"},{"@type":"ListItem","position":3,"name":"implantation-jour-florium-mayflower70LD-de"}]},{"@type":"WebSite","@id":"https:\/\/www.fleurette-florium.fr\/#website","url":"https:\/\/www.fleurette-florium.fr\/","name":"Fleurette Florium","description":"","publisher":{"@id":"https:\/\/www.fleurette-florium.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fleurette-florium.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/www.fleurette-florium.fr\/#organization","name":"Fleurette Florium","url":"https:\/\/www.fleurette-florium.fr\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/www.fleurette-florium.fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2021\/07\/logo-fleurette-florium-scaled.png","contentUrl":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2021\/07\/logo-fleurette-florium-scaled.png","width":2560,"height":830,"caption":"Fleurette Florium"},"image":{"@id":"https:\/\/www.fleurette-florium.fr\/#\/schema\/logo\/image\/"}}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2022\/08\/implantation-jour-florium-mayflower70LD-de.png'><img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2022\/08\/implantation-jour-florium-mayflower70LD-de-300x300.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2022\/08\/implantation-jour-florium-mayflower70LD-de-300x300.png 300w, https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2022\/08\/implantation-jour-florium-mayflower70LD-de-150x150.png 150w, https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2022\/08\/implantation-jour-florium-mayflower70LD-de-768x768.png 768w, https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2022\/08\/implantation-jour-florium-mayflower70LD-de-700x700.png 700w, https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2022\/08\/implantation-jour-florium-mayflower70LD-de.png 900w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/png","media_details":{"width":900,"height":900,"file":"2022\/08\/implantation-jour-florium-mayflower70LD-de.png","sizes":{"medium":{"file":"implantation-jour-florium-mayflower70LD-de-300x300.png","width":300,"height":300,"mime_type":"image\/png","source_url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2022\/08\/implantation-jour-florium-mayflower70LD-de-300x300.png"},"thumbnail":{"file":"implantation-jour-florium-mayflower70LD-de-150x150.png","width":150,"height":150,"mime_type":"image\/png","source_url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2022\/08\/implantation-jour-florium-mayflower70LD-de-150x150.png"},"medium_large":{"file":"implantation-jour-florium-mayflower70LD-de-768x768.png","width":768,"height":768,"mime_type":"image\/png","source_url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2022\/08\/implantation-jour-florium-mayflower70LD-de-768x768.png"},"tp-image-grid":{"file":"implantation-jour-florium-mayflower70LD-de-700x700.png","width":700,"height":700,"mime_type":"image\/png","source_url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2022\/08\/implantation-jour-florium-mayflower70LD-de-700x700.png"},"full":{"file":"implantation-jour-florium-mayflower70LD-de.png","width":900,"height":900,"mime_type":"image\/png","source_url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2022\/08\/implantation-jour-florium-mayflower70LD-de.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":2521,"source_url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2022\/08\/implantation-jour-florium-mayflower70LD-de.png","_links":{"self":[{"href":"https:\/\/www.fleurette-florium.fr\/nl\/wp-json\/wp\/v2\/media\/21864","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fleurette-florium.fr\/nl\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.fleurette-florium.fr\/nl\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.fleurette-florium.fr\/nl\/wp-json\/wp\/v2\/users\/6685"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fleurette-florium.fr\/nl\/wp-json\/wp\/v2\/comments?post=21864"}],"wp:term":[{"taxonomy":"media_folder","embeddable":true,"href":"https:\/\/www.fleurette-florium.fr\/nl\/wp-json\/wp\/v2\/media_folder?post=21864"}],"wp:attached-to":[{"embeddable":true,"post_type":"page","id":2521,"href":"https:\/\/www.fleurette-florium.fr\/nl\/wp-json\/wp\/v2\/pages\/2521"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}