{"id":23168,"date":"2022-11-15T22:35:36","date_gmt":"2022-11-15T21:35:36","guid":{"rendered":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2022\/11\/slider-mayflower_1980x550-fleurette-florium-gb.jpg"},"modified":"2022-11-15T22:35:36","modified_gmt":"2022-11-15T21:35:36","slug":"slider-mayflower_1980x550-fleurette-florium-gb-2","status":"inherit","type":"attachment","link":"https:\/\/www.fleurette-florium.fr\/es\/gamme-magister-perfilados-con-cama-de-techo\/slider-mayflower_1980x550-fleurette-florium-gb-2\/","title":{"rendered":"slider-mayflower_1980x550-fleurette-florium-gb"},"author":6685,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"media_folder":[],"class_list":["post-23168","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>slider-mayflower_1980x550-fleurette-florium-gb - Fleurette Florium<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2022\/11\/slider-mayflower_1980x550-fleurette-florium-gb.jpg\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"slider-mayflower_1980x550-fleurette-florium-gb - Fleurette Florium\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2022\/11\/slider-mayflower_1980x550-fleurette-florium-gb.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Fleurette Florium\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2022\/11\/slider-mayflower_1980x550-fleurette-florium-gb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1980\" \/>\n\t<meta property=\"og:image:height\" content=\"550\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/slider-mayflower_1980x550-fleurette-florium-gb.jpg\",\"url\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/slider-mayflower_1980x550-fleurette-florium-gb.jpg\",\"name\":\"slider-mayflower_1980x550-fleurette-florium-gb - Fleurette Florium\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/#website\"},\"datePublished\":\"2022-11-15T21:35:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/slider-mayflower_1980x550-fleurette-florium-gb.jpg#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fleurette-florium.fr\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/slider-mayflower_1980x550-fleurette-florium-gb.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/slider-mayflower_1980x550-fleurette-florium-gb.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\",\"item\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gama Magister &#8211; Perfilados con cama de techo\",\"item\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/es\\\/gamme-magister-perfilados-con-cama-de-techo\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"slider-mayflower_1980x550-fleurette-florium-gb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/#website\",\"url\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/\",\"name\":\"Fleurette Florium\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/#organization\",\"name\":\"Fleurette Florium\",\"url\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/logo-fleurette-florium-scaled.png\",\"contentUrl\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/logo-fleurette-florium-scaled.png\",\"width\":2560,\"height\":830,\"caption\":\"Fleurette Florium\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"slider-mayflower_1980x550-fleurette-florium-gb - Fleurette Florium","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2022\/11\/slider-mayflower_1980x550-fleurette-florium-gb.jpg","og_locale":"es_ES","og_type":"article","og_title":"slider-mayflower_1980x550-fleurette-florium-gb - Fleurette Florium","og_url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2022\/11\/slider-mayflower_1980x550-fleurette-florium-gb.jpg","og_site_name":"Fleurette Florium","og_image":[{"width":1980,"height":550,"url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2022\/11\/slider-mayflower_1980x550-fleurette-florium-gb.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2022\/11\/slider-mayflower_1980x550-fleurette-florium-gb.jpg","url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2022\/11\/slider-mayflower_1980x550-fleurette-florium-gb.jpg","name":"slider-mayflower_1980x550-fleurette-florium-gb - Fleurette Florium","isPartOf":{"@id":"https:\/\/www.fleurette-florium.fr\/#website"},"datePublished":"2022-11-15T21:35:36+00:00","breadcrumb":{"@id":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2022\/11\/slider-mayflower_1980x550-fleurette-florium-gb.jpg#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2022\/11\/slider-mayflower_1980x550-fleurette-florium-gb.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2022\/11\/slider-mayflower_1980x550-fleurette-florium-gb.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"","item":"https:\/\/www.fleurette-florium.fr\/es\/"},{"@type":"ListItem","position":2,"name":"Gama Magister &#8211; Perfilados con cama de techo","item":"https:\/\/www.fleurette-florium.fr\/es\/gamme-magister-perfilados-con-cama-de-techo\/"},{"@type":"ListItem","position":3,"name":"slider-mayflower_1980x550-fleurette-florium-gb"}]},{"@type":"WebSite","@id":"https:\/\/www.fleurette-florium.fr\/#website","url":"https:\/\/www.fleurette-florium.fr\/","name":"Fleurette Florium","description":"","publisher":{"@id":"https:\/\/www.fleurette-florium.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fleurette-florium.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.fleurette-florium.fr\/#organization","name":"Fleurette Florium","url":"https:\/\/www.fleurette-florium.fr\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.fleurette-florium.fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2021\/07\/logo-fleurette-florium-scaled.png","contentUrl":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2021\/07\/logo-fleurette-florium-scaled.png","width":2560,"height":830,"caption":"Fleurette Florium"},"image":{"@id":"https:\/\/www.fleurette-florium.fr\/#\/schema\/logo\/image\/"}}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2022\/11\/slider-mayflower_1980x550-fleurette-florium-gb.jpg'><img decoding=\"async\" width=\"300\" height=\"83\" src=\"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2022\/11\/slider-mayflower_1980x550-fleurette-florium-gb-300x83.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2022\/11\/slider-mayflower_1980x550-fleurette-florium-gb-300x83.jpg 300w, https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2022\/11\/slider-mayflower_1980x550-fleurette-florium-gb-1024x284.jpg 1024w, https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2022\/11\/slider-mayflower_1980x550-fleurette-florium-gb-768x213.jpg 768w, https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2022\/11\/slider-mayflower_1980x550-fleurette-florium-gb-1536x427.jpg 1536w, https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2022\/11\/slider-mayflower_1980x550-fleurette-florium-gb.jpg 1980w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1980,"height":550,"file":"2022\/11\/slider-mayflower_1980x550-fleurette-florium-gb.jpg","filesize":657359,"sizes":{"medium":{"file":"slider-mayflower_1980x550-fleurette-florium-gb-300x83.jpg","width":300,"height":83,"filesize":7355,"mime_type":"image\/jpeg","source_url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2022\/11\/slider-mayflower_1980x550-fleurette-florium-gb-300x83.jpg"},"large":{"file":"slider-mayflower_1980x550-fleurette-florium-gb-1024x284.jpg","width":1024,"height":284,"filesize":57608,"mime_type":"image\/jpeg","source_url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2022\/11\/slider-mayflower_1980x550-fleurette-florium-gb-1024x284.jpg"},"thumbnail":{"file":"slider-mayflower_1980x550-fleurette-florium-gb-150x150.jpg","width":150,"height":150,"filesize":6342,"mime_type":"image\/jpeg","source_url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2022\/11\/slider-mayflower_1980x550-fleurette-florium-gb-150x150.jpg"},"medium_large":{"file":"slider-mayflower_1980x550-fleurette-florium-gb-768x213.jpg","width":768,"height":213,"filesize":34471,"mime_type":"image\/jpeg","source_url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2022\/11\/slider-mayflower_1980x550-fleurette-florium-gb-768x213.jpg"},"1536x1536":{"file":"slider-mayflower_1980x550-fleurette-florium-gb-1536x427.jpg","width":1536,"height":427,"filesize":119432,"mime_type":"image\/jpeg","source_url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2022\/11\/slider-mayflower_1980x550-fleurette-florium-gb-1536x427.jpg"},"tp-image-grid":{"file":"slider-mayflower_1980x550-fleurette-florium-gb-700x550.jpg","width":700,"height":550,"filesize":88257,"mime_type":"image\/jpeg","source_url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2022\/11\/slider-mayflower_1980x550-fleurette-florium-gb-700x550.jpg"},"cmplz_banner_image":{"file":"slider-mayflower_1980x550-fleurette-florium-gb-350x100.jpg","width":350,"height":100,"filesize":9722,"mime_type":"image\/jpeg","source_url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2022\/11\/slider-mayflower_1980x550-fleurette-florium-gb-350x100.jpg"},"full":{"file":"slider-mayflower_1980x550-fleurette-florium-gb.jpg","width":1980,"height":550,"mime_type":"image\/jpeg","source_url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2022\/11\/slider-mayflower_1980x550-fleurette-florium-gb.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":15016,"source_url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2022\/11\/slider-mayflower_1980x550-fleurette-florium-gb.jpg","filename":"slider-mayflower_1980x550-fleurette-florium-gb.jpg","filesize":657359,"_links":{"self":[{"href":"https:\/\/www.fleurette-florium.fr\/es\/wp-json\/wp\/v2\/media\/23168","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fleurette-florium.fr\/es\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.fleurette-florium.fr\/es\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.fleurette-florium.fr\/es\/wp-json\/wp\/v2\/users\/6685"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fleurette-florium.fr\/es\/wp-json\/wp\/v2\/comments?post=23168"}],"wp:term":[{"taxonomy":"media_folder","embeddable":true,"href":"https:\/\/www.fleurette-florium.fr\/es\/wp-json\/wp\/v2\/media_folder?post=23168"}],"wp:attached-to":[{"embeddable":true,"post_type":"page","id":15016,"href":"https:\/\/www.fleurette-florium.fr\/es\/wp-json\/wp\/v2\/pages\/15016"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}