{"id":15444,"date":"2020-03-24T20:29:42","date_gmt":"2020-03-24T19:29:42","guid":{"rendered":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2020\/03\/70-ld-article-page2.png"},"modified":"2020-03-24T20:31:50","modified_gmt":"2020-03-24T19:31:50","slug":"70-ld-article-page2-2","status":"inherit","type":"attachment","link":"https:\/\/www.fleurette-florium.fr\/es\/70-ld-article-page2-2\/","title":{"rendered":"70-ld-article-page2"},"author":67182,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"media_folder":[],"class_list":["post-15444","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>70-ld-article-page2 - Fleurette Florium<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2020\/03\/70-ld-article-page2.png\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"70-ld-article-page2 - Fleurette Florium\" \/>\n<meta property=\"og:description\" content=\"Seite 2\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2020\/03\/70-ld-article-page2.png\" \/>\n<meta property=\"og:site_name\" content=\"Fleurette Florium\" \/>\n<meta property=\"article:modified_time\" content=\"2020-03-24T19:31:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2020\/03\/70-ld-article-page2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"567\" \/>\n\t<meta property=\"og:image:height\" content=\"776\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/70-ld-article-page2.png\",\"url\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/70-ld-article-page2.png\",\"name\":\"70-ld-article-page2 - Fleurette Florium\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/#website\"},\"datePublished\":\"2020-03-24T19:29:42+00:00\",\"dateModified\":\"2020-03-24T19:31:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/70-ld-article-page2.png#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fleurette-florium.fr\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/70-ld-article-page2.png\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/70-ld-article-page2.png#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\",\"item\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/es\\\/accueil-camping-cars-modernes-florium\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"70-ld-article-page2\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/#website\",\"url\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/\",\"name\":\"Fleurette Florium\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/#organization\",\"name\":\"Fleurette Florium\",\"url\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/logo-fleurette-florium-scaled.png\",\"contentUrl\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/logo-fleurette-florium-scaled.png\",\"width\":2560,\"height\":830,\"caption\":\"Fleurette Florium\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"70-ld-article-page2 - Fleurette Florium","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2020\/03\/70-ld-article-page2.png","og_locale":"es_ES","og_type":"article","og_title":"70-ld-article-page2 - Fleurette Florium","og_description":"Seite 2","og_url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2020\/03\/70-ld-article-page2.png","og_site_name":"Fleurette Florium","article_modified_time":"2020-03-24T19:31:50+00:00","og_image":[{"width":567,"height":776,"url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2020\/03\/70-ld-article-page2.png","type":"image\/png"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2020\/03\/70-ld-article-page2.png","url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2020\/03\/70-ld-article-page2.png","name":"70-ld-article-page2 - Fleurette Florium","isPartOf":{"@id":"https:\/\/www.fleurette-florium.fr\/#website"},"datePublished":"2020-03-24T19:29:42+00:00","dateModified":"2020-03-24T19:31:50+00:00","breadcrumb":{"@id":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2020\/03\/70-ld-article-page2.png#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2020\/03\/70-ld-article-page2.png"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2020\/03\/70-ld-article-page2.png#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"","item":"https:\/\/www.fleurette-florium.fr\/es\/accueil-camping-cars-modernes-florium\/"},{"@type":"ListItem","position":2,"name":"70-ld-article-page2"}]},{"@type":"WebSite","@id":"https:\/\/www.fleurette-florium.fr\/#website","url":"https:\/\/www.fleurette-florium.fr\/","name":"Fleurette Florium","description":"","publisher":{"@id":"https:\/\/www.fleurette-florium.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fleurette-florium.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.fleurette-florium.fr\/#organization","name":"Fleurette Florium","url":"https:\/\/www.fleurette-florium.fr\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.fleurette-florium.fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2021\/07\/logo-fleurette-florium-scaled.png","contentUrl":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2021\/07\/logo-fleurette-florium-scaled.png","width":2560,"height":830,"caption":"Fleurette Florium"},"image":{"@id":"https:\/\/www.fleurette-florium.fr\/#\/schema\/logo\/image\/"}}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2020\/03\/70-ld-article-page2.png'><img fetchpriority=\"high\" decoding=\"async\" width=\"219\" height=\"300\" src=\"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2020\/03\/70-ld-article-page2-219x300.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2020\/03\/70-ld-article-page2-219x300.png 219w, https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2020\/03\/70-ld-article-page2.png 567w\" sizes=\"(max-width: 219px) 100vw, 219px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>Seite 2<\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/png","media_details":{"width":567,"height":776,"file":"2020\/03\/70-ld-article-page2.png","sizes":{"medium":{"file":"70-ld-article-page2-219x300.png","width":219,"height":300,"mime_type":"image\/png","source_url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2020\/03\/70-ld-article-page2-219x300.png"},"thumbnail":{"file":"70-ld-article-page2-150x150.png","width":150,"height":150,"mime_type":"image\/png","source_url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2020\/03\/70-ld-article-page2-150x150.png"},"related_portfolio":{"file":"70-ld-article-page2-270x140.png","width":270,"height":140,"mime_type":"image\/png","source_url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2020\/03\/70-ld-article-page2-270x140.png"},"auto_thumb":{"file":"70-ld-article-page2-167x119.png","width":167,"height":119,"mime_type":"image\/png","source_url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2020\/03\/70-ld-article-page2-167x119.png"},"auto_slider":{"file":"70-ld-article-page2-567x456.png","width":567,"height":456,"mime_type":"image\/png","source_url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2020\/03\/70-ld-article-page2-567x456.png"},"auto_listing":{"file":"70-ld-article-page2-200x150.png","width":200,"height":150,"mime_type":"image\/png","source_url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2020\/03\/70-ld-article-page2-200x150.png"},"auto_portfolio":{"file":"70-ld-article-page2-567x450.png","width":567,"height":450,"mime_type":"image\/png","source_url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2020\/03\/70-ld-article-page2-567x450.png"},"large_featured_image":{"file":"70-ld-article-page2-567x250.png","width":567,"height":250,"mime_type":"image\/png","source_url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2020\/03\/70-ld-article-page2-567x250.png"},"full":{"file":"70-ld-article-page2.png","width":567,"height":776,"mime_type":"image\/png","source_url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2020\/03\/70-ld-article-page2.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2020\/03\/70-ld-article-page2.png","_links":{"self":[{"href":"https:\/\/www.fleurette-florium.fr\/es\/wp-json\/wp\/v2\/media\/15444","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fleurette-florium.fr\/es\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.fleurette-florium.fr\/es\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.fleurette-florium.fr\/es\/wp-json\/wp\/v2\/users\/67182"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fleurette-florium.fr\/es\/wp-json\/wp\/v2\/comments?post=15444"}],"wp:term":[{"taxonomy":"media_folder","embeddable":true,"href":"https:\/\/www.fleurette-florium.fr\/es\/wp-json\/wp\/v2\/media_folder?post=15444"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}