{"id":27807,"date":"2024-08-21T09:24:59","date_gmt":"2024-08-21T08:24:59","guid":{"rendered":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2024\/08\/NL-slider-homepage-2025-fleurette-florium-1.jpg"},"modified":"2024-08-21T09:24:59","modified_gmt":"2024-08-21T08:24:59","slug":"nl-slider-homepage-2025-fleurette-florium-1-2","status":"inherit","type":"attachment","link":"https:\/\/www.fleurette-florium.fr\/en\/nl-slider-homepage-2025-fleurette-florium-1-2\/","title":{"rendered":"NL-slider-homepage-2025-fleurette-florium-1"},"author":52637,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"media_folder":[],"class_list":["post-27807","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>NL-slider-homepage-2025-fleurette-florium-1 - Fleurette Florium<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2024\/08\/NL-slider-homepage-2025-fleurette-florium-1.jpg\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NL-slider-homepage-2025-fleurette-florium-1 - Fleurette Florium\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2024\/08\/NL-slider-homepage-2025-fleurette-florium-1.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Fleurette Florium\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2024\/08\/NL-slider-homepage-2025-fleurette-florium-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1980\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/NL-slider-homepage-2025-fleurette-florium-1.jpg\",\"url\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/NL-slider-homepage-2025-fleurette-florium-1.jpg\",\"name\":\"NL-slider-homepage-2025-fleurette-florium-1 - Fleurette Florium\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/#website\"},\"datePublished\":\"2024-08-21T08:24:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/NL-slider-homepage-2025-fleurette-florium-1.jpg#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fleurette-florium.fr\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/NL-slider-homepage-2025-fleurette-florium-1.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/NL-slider-homepage-2025-fleurette-florium-1.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\",\"item\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/en\\\/sample-page-2\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NL-slider-homepage-2025-fleurette-florium-1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/#website\",\"url\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/\",\"name\":\"Fleurette Florium\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/#organization\",\"name\":\"Fleurette Florium\",\"url\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/logo-fleurette-florium-scaled.png\",\"contentUrl\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/logo-fleurette-florium-scaled.png\",\"width\":2560,\"height\":830,\"caption\":\"Fleurette Florium\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"NL-slider-homepage-2025-fleurette-florium-1 - Fleurette Florium","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2024\/08\/NL-slider-homepage-2025-fleurette-florium-1.jpg","og_locale":"en_US","og_type":"article","og_title":"NL-slider-homepage-2025-fleurette-florium-1 - Fleurette Florium","og_url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2024\/08\/NL-slider-homepage-2025-fleurette-florium-1.jpg","og_site_name":"Fleurette Florium","og_image":[{"width":1980,"height":600,"url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2024\/08\/NL-slider-homepage-2025-fleurette-florium-1.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2024\/08\/NL-slider-homepage-2025-fleurette-florium-1.jpg","url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2024\/08\/NL-slider-homepage-2025-fleurette-florium-1.jpg","name":"NL-slider-homepage-2025-fleurette-florium-1 - Fleurette Florium","isPartOf":{"@id":"https:\/\/www.fleurette-florium.fr\/#website"},"datePublished":"2024-08-21T08:24:59+00:00","breadcrumb":{"@id":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2024\/08\/NL-slider-homepage-2025-fleurette-florium-1.jpg#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2024\/08\/NL-slider-homepage-2025-fleurette-florium-1.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2024\/08\/NL-slider-homepage-2025-fleurette-florium-1.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"","item":"https:\/\/www.fleurette-florium.fr\/en\/sample-page-2\/"},{"@type":"ListItem","position":2,"name":"NL-slider-homepage-2025-fleurette-florium-1"}]},{"@type":"WebSite","@id":"https:\/\/www.fleurette-florium.fr\/#website","url":"https:\/\/www.fleurette-florium.fr\/","name":"Fleurette Florium","description":"","publisher":{"@id":"https:\/\/www.fleurette-florium.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fleurette-florium.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.fleurette-florium.fr\/#organization","name":"Fleurette Florium","url":"https:\/\/www.fleurette-florium.fr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.fleurette-florium.fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2021\/07\/logo-fleurette-florium-scaled.png","contentUrl":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2021\/07\/logo-fleurette-florium-scaled.png","width":2560,"height":830,"caption":"Fleurette Florium"},"image":{"@id":"https:\/\/www.fleurette-florium.fr\/#\/schema\/logo\/image\/"}}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2024\/08\/NL-slider-homepage-2025-fleurette-florium-1.jpg'><img decoding=\"async\" width=\"300\" height=\"91\" src=\"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2024\/08\/NL-slider-homepage-2025-fleurette-florium-1-300x91.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2024\/08\/NL-slider-homepage-2025-fleurette-florium-1-300x91.jpg 300w, https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2024\/08\/NL-slider-homepage-2025-fleurette-florium-1-1024x310.jpg 1024w, https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2024\/08\/NL-slider-homepage-2025-fleurette-florium-1-768x233.jpg 768w, https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2024\/08\/NL-slider-homepage-2025-fleurette-florium-1-1536x465.jpg 1536w, https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2024\/08\/NL-slider-homepage-2025-fleurette-florium-1.jpg 1980w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1980,"height":600,"file":"2024\/08\/NL-slider-homepage-2025-fleurette-florium-1.jpg","filesize":375721,"sizes":{"medium":{"file":"NL-slider-homepage-2025-fleurette-florium-1-300x91.jpg","width":300,"height":91,"filesize":21040,"mime_type":"image\/jpeg","source_url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2024\/08\/NL-slider-homepage-2025-fleurette-florium-1-300x91.jpg"},"large":{"file":"NL-slider-homepage-2025-fleurette-florium-1-1024x310.jpg","width":1024,"height":310,"filesize":78780,"mime_type":"image\/jpeg","source_url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2024\/08\/NL-slider-homepage-2025-fleurette-florium-1-1024x310.jpg"},"thumbnail":{"file":"NL-slider-homepage-2025-fleurette-florium-1-150x150.jpg","width":150,"height":150,"filesize":19266,"mime_type":"image\/jpeg","source_url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2024\/08\/NL-slider-homepage-2025-fleurette-florium-1-150x150.jpg"},"medium_large":{"file":"NL-slider-homepage-2025-fleurette-florium-1-768x233.jpg","width":768,"height":233,"filesize":53394,"mime_type":"image\/jpeg","source_url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2024\/08\/NL-slider-homepage-2025-fleurette-florium-1-768x233.jpg"},"1536x1536":{"file":"NL-slider-homepage-2025-fleurette-florium-1-1536x465.jpg","width":1536,"height":465,"filesize":141752,"mime_type":"image\/jpeg","source_url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2024\/08\/NL-slider-homepage-2025-fleurette-florium-1-1536x465.jpg"},"tp-image-grid":{"file":"NL-slider-homepage-2025-fleurette-florium-1-700x600.jpg","width":700,"height":600,"filesize":102141,"mime_type":"image\/jpeg","source_url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2024\/08\/NL-slider-homepage-2025-fleurette-florium-1-700x600.jpg"},"cmplz_banner_image":{"file":"NL-slider-homepage-2025-fleurette-florium-1-350x100.jpg","width":350,"height":100,"filesize":23073,"mime_type":"image\/jpeg","source_url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2024\/08\/NL-slider-homepage-2025-fleurette-florium-1-350x100.jpg"},"full":{"file":"NL-slider-homepage-2025-fleurette-florium-1.jpg","width":1980,"height":600,"mime_type":"image\/jpeg","source_url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2024\/08\/NL-slider-homepage-2025-fleurette-florium-1.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2024\/08\/NL-slider-homepage-2025-fleurette-florium-1.jpg","_links":{"self":[{"href":"https:\/\/www.fleurette-florium.fr\/en\/wp-json\/wp\/v2\/media\/27807","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fleurette-florium.fr\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.fleurette-florium.fr\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.fleurette-florium.fr\/en\/wp-json\/wp\/v2\/users\/52637"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fleurette-florium.fr\/en\/wp-json\/wp\/v2\/comments?post=27807"}],"wp:term":[{"taxonomy":"media_folder","embeddable":true,"href":"https:\/\/www.fleurette-florium.fr\/en\/wp-json\/wp\/v2\/media_folder?post=27807"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}