{"id":29471,"date":"2024-10-02T09:58:59","date_gmt":"2024-10-02T08:58:59","guid":{"rendered":"https:\/\/www.fleurette-florium.fr\/?p=29471"},"modified":"2024-10-02T10:44:28","modified_gmt":"2024-10-02T09:44:28","slug":"neu-der-camper-van-black-pearl-by-florium","status":"publish","type":"post","link":"https:\/\/www.fleurette-florium.fr\/de\/neu-der-camper-van-black-pearl-by-florium\/","title":{"rendered":"Neu: Der Camper Van BLACK PEARL by Florium"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"29471\" class=\"elementor elementor-29471 elementor-29089\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c60c431 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c60c431\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6363aa0\" data-id=\"6363aa0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-56c22e1 elementor-widget elementor-widget-image\" data-id=\"56c22e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1980\" height=\"619\" src=\"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2024\/10\/header-black-pearl-actu-florium-DE.jpg\" class=\"attachment-full size-full wp-image-29589\" alt=\"\" srcset=\"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2024\/10\/header-black-pearl-actu-florium-DE.jpg 1980w, https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2024\/10\/header-black-pearl-actu-florium-DE-300x94.jpg 300w, https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2024\/10\/header-black-pearl-actu-florium-DE-1024x320.jpg 1024w, https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2024\/10\/header-black-pearl-actu-florium-DE-768x240.jpg 768w, https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2024\/10\/header-black-pearl-actu-florium-DE-1536x480.jpg 1536w\" sizes=\"(max-width: 1980px) 100vw, 1980px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5072c4d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5072c4d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5a1fa98\" data-id=\"5a1fa98\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3edd06d elementor-widget elementor-widget-spacer\" data-id=\"3edd06d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a98f5ec elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a98f5ec\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ed644e0\" data-id=\"ed644e0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2a078bb elementor-widget elementor-widget-heading\" data-id=\"2a078bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Neu: Der Camper Van BLACK PEARL by Florium<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3e715ab2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3e715ab2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-21db9b0c\" data-id=\"21db9b0c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4066d9e4 elementor-widget elementor-widget-text-editor\" data-id=\"4066d9e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Die Marke Florium steigt mit ihrem brandneuen Camper Van BLACK PEARL in den Camper-Van-Sektor ein. Zwei Fahrzeuge werden vorab auf der Freizeitfahrzeugmesse in Paris-Villepinte vom 21. bis zum 29. September vorgestellt. Unser Team erwartet Sie im Ausstellungsbereich Fleurette-Florium HALLE 5A, Stand C8!<\/strong><\/p><p>Mit diesem neuen Fahrzeug auf Fiat-Ducato-Tr\u00e4gerfahrzeug spricht Florium eine neue, j\u00fcngere Kundschaft an. Die Manufaktur Fleurette Constructeur \u00fcbertr\u00e4gt damit ihr langj\u00e4hriges Know-how auf den Bereich der Reisemobile und Vans mit Aufstelldach.<\/p><p>BLACK PEARL by Florium st\u00fctzt sich auf die Grundlagen der Marke: ein Netz von Vertriebspartnern in Frankreich und Europa, eine Positionierung im oberen Preissegment, franz\u00f6sischer Chic mit handgefertigten M\u00f6beln und einer exklusiven, hochwertigen Polsterung. Diese starken Argumente werden den neuen Camper Van zu einem vollen Erfolg machen.<\/p><p>Der BLACK PEARL Camper Van wird in zwei L\u00e4ngen und zwei Grundrissen angeboten\u00a0\u2013 mit einem Querbett im Heck oder mit Einzelbetten\u00a0\u2013 und ist ab 69.950\u00a0Euro (inkl. MwSt.) erh\u00e4ltlich.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-519cce3e\" data-id=\"519cce3e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5273047 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"5273047\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"618\" height=\"464\" src=\"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2024\/09\/salon-fourgon-black-pearl-florium-1.png\" class=\"attachment-large size-large wp-image-29119\" alt=\"\" srcset=\"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2024\/09\/salon-fourgon-black-pearl-florium-1.png 618w, https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2024\/09\/salon-fourgon-black-pearl-florium-1-300x225.png 300w\" sizes=\"(max-width: 618px) 100vw, 618px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-704068b elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"704068b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-80bdd74\" data-id=\"80bdd74\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-80f9627 elementor-widget elementor-widget-heading\" data-id=\"80f9627\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Camper Van BLACK PEARL 59LT<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b12c675 elementor-widget elementor-widget-text-editor\" data-id=\"b12c675\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>mit Querbett im Heck<br \/>L\u00e4nge: 5,99\u00a0m, H\u00f6he 2,59\u00a0m<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7e286f34 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"7e286f34\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"764\" src=\"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2024\/09\/59LT_Florium_2024_2-1024x978.png\" class=\"attachment-large size-large wp-image-29139\" alt=\"\" srcset=\"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2024\/09\/59LT_Florium_2024_2-1024x978.png 1024w, https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2024\/09\/59LT_Florium_2024_2-300x286.png 300w, https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2024\/09\/59LT_Florium_2024_2-768x733.png 768w, https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2024\/09\/59LT_Florium_2024_2-1536x1467.png 1536w, https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2024\/09\/59LT_Florium_2024_2-2048x1956.png 2048w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-61a4a5d\" data-id=\"61a4a5d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-774237c elementor-widget elementor-widget-heading\" data-id=\"774237c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Camper Van BLACK PEARL 63LJ<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-41188af elementor-widget elementor-widget-text-editor\" data-id=\"41188af\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>mit Einzelbetten im Heck<br \/>L\u00e4nge: 6,36\u00a0m, H\u00f6he 2,59\u00a0m<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-46161cf elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"46161cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"727\" src=\"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2024\/09\/63LJ_Florium_2024_2-1024x931.png\" class=\"attachment-large size-large wp-image-29144\" alt=\"\" srcset=\"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2024\/09\/63LJ_Florium_2024_2-1024x931.png 1024w, https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2024\/09\/63LJ_Florium_2024_2-300x273.png 300w, https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2024\/09\/63LJ_Florium_2024_2-768x698.png 768w, https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2024\/09\/63LJ_Florium_2024_2-1536x1397.png 1536w, https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2024\/09\/63LJ_Florium_2024_2-2048x1862.png 2048w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3b141b31 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3b141b31\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-4f82b4c9\" data-id=\"4f82b4c9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-287e32a9 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"287e32a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"300\" src=\"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2024\/09\/cuisine-fourgon-black-pearl-florium-225x300.jpg\" class=\"attachment-medium size-medium wp-image-29104\" alt=\"\" srcset=\"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2024\/09\/cuisine-fourgon-black-pearl-florium-225x300.jpg 225w, https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2024\/09\/cuisine-fourgon-black-pearl-florium-768x1024.jpg 768w, https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2024\/09\/cuisine-fourgon-black-pearl-florium-1152x1536.jpg 1152w, https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2024\/09\/cuisine-fourgon-black-pearl-florium.jpg 1512w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-facf3a4\" data-id=\"facf3a4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1fdebce elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"1fdebce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"300\" src=\"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2024\/09\/salon-fourgon-black-pearl-florium-2-225x300.jpg\" class=\"attachment-medium size-medium wp-image-29124\" alt=\"\" srcset=\"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2024\/09\/salon-fourgon-black-pearl-florium-2-225x300.jpg 225w, https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2024\/09\/salon-fourgon-black-pearl-florium-2-768x1024.jpg 768w, https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2024\/09\/salon-fourgon-black-pearl-florium-2-1152x1536.jpg 1152w, https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2024\/09\/salon-fourgon-black-pearl-florium-2.jpg 1512w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-19ca6657\" data-id=\"19ca6657\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6b514d94 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6b514d94\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-1b6d55c\" data-id=\"1b6d55c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-543b681 elementor-widget elementor-widget-heading\" data-id=\"543b681\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Die Vorteile des Camper Vans\nBLACK PEARL mit 4 Pl\u00e4tzen\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6063a848 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"6063a848\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die Highlights:<\/p><ul><li>Das Skyview f\u00fcr nat\u00fcrliches Licht und ein gro\u00dfartiges Raumgef\u00fchl<\/li><li>Die funktionale K\u00fcche mit zahlreichen Staur\u00e4umen<\/li><li>Der gro\u00dfe Kompressionsk\u00fchlschrank (135\u00a0L), f\u00fcr Energieautonomie auch auf l\u00e4ngere Reisen<\/li><li>Der Komfort der Truma 4D Dieselheizung, auch bei sehr kaltem Wetter, dank optimaler Isolierung<\/li><li>Das Tastenfeld am Lenkrad<\/li><li>Die ausgesprochen moderne Innenausstattung und Polsterung \u201eBlack Pearl\u201c<\/li><li>Die 4 verf\u00fcgbaren Karosseriefarben<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-88d5350 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"88d5350\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a72fa28\" data-id=\"a72fa28\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8991d94 elementor-widget elementor-widget-heading\" data-id=\"8991d94\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Der Camper Van BLACK PEARL:<br> \nKomfortabel Reisen im Kompaktformat\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a77ee71 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"a77ee71\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Beide Modelle bieten vier zugelassene Sitzpl\u00e4tze und drei Schlafpl\u00e4tze (oder f\u00fcr zwei Erwachsene und zwei Kinder)<\/p><p>Der K\u00fcchenblock befindet sich am Eingang des Fahrzeugs auf der linken Seite, mit daran anschlie\u00dfendem K\u00fchlschrank. Die Sitzgruppe befindet sich vorne, mit einer Sitzbank mit zwei Sitzpl\u00e4tzen in Fahrtrichtung und zwei drehbaren Fahrerhaussitzen.<\/p><p>Einfallsreich: Das Badezimmer mit Vario-System erm\u00f6glicht es, einen Dusch- oder einen Toilettenbereich zu schaffen. Eine zentrale Wand mit Spiegel-Waschbecken l\u00e4sst sich drehen, um die ger\u00e4umige und praktische Toilette in eine komfortable und freistehende Duschkabine umzuwandeln.<\/p><p>Florium steht auch f\u00fcr verantwortungsbewusstes Reisen mit saubereren, kraftstoff- und energiesparenden Technologien, um unabh\u00e4ngig zu leben und gleichzeitig die Umwelt zu schonen. Die BLACK PEARL-Modelle sind mit einer 100 Ah Lithium-Batterie, einem Kompressionsk\u00fchlschrank und einer 100\u00a0% LED-Beleuchtung ausgestattet.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d44332d elementor-widget elementor-widget-spacer\" data-id=\"d44332d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a73f214 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"a73f214\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Wenden Sie sich an einen Partnerh\u00e4ndler in Ihrer N\u00e4he.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5df924c elementor-widget elementor-widget-button\" data-id=\"5df924c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.fleurette-florium.fr\/de\/handler\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">H\u00e4ndler suchen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ab0a8dd\" data-id=\"ab0a8dd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-56177cc elementor-widget__width-initial elementor-widget elementor-widget-gallery\" data-id=\"56177cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;gallery_layout&quot;:&quot;justified&quot;,&quot;ideal_row_height&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:296,&quot;sizes&quot;:[]},&quot;gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:20,&quot;sizes&quot;:[]},&quot;lazyload&quot;:&quot;yes&quot;,&quot;ideal_row_height_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:150,&quot;sizes&quot;:[]},&quot;ideal_row_height_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:150,&quot;sizes&quot;:[]},&quot;gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;link_to&quot;:&quot;file&quot;,&quot;overlay_background&quot;:&quot;yes&quot;,&quot;content_hover_animation&quot;:&quot;fade-in&quot;}\" data-widget_type=\"gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-gallery__container\">\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2024\/09\/sdb-fourgon-black-pearl-florium-2.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"56177cc\" data-elementor-lightbox-title=\"sdb-fourgon-black-pearl-florium-2\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjkxMzQsInVybCI6Imh0dHBzOlwvXC93d3cuZmxldXJldHRlLWZsb3JpdW0uZnJcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzA5XC9zZGItZm91cmdvbi1ibGFjay1wZWFybC1mbG9yaXVtLTIuanBnIiwic2xpZGVzaG93IjoiNTYxNzdjYyJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2024\/09\/sdb-fourgon-black-pearl-florium-2-225x300.jpg\" data-width=\"225\" data-height=\"300\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2024\/09\/sdb-fourgon-black-pearl-florium-1.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"56177cc\" data-elementor-lightbox-title=\"sdb-fourgon-black-pearl-florium-1\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjkxMjksInVybCI6Imh0dHBzOlwvXC93d3cuZmxldXJldHRlLWZsb3JpdW0uZnJcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzA5XC9zZGItZm91cmdvbi1ibGFjay1wZWFybC1mbG9yaXVtLTEuanBnIiwic2xpZGVzaG93IjoiNTYxNzdjYyJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2024\/09\/sdb-fourgon-black-pearl-florium-1-225x300.jpg\" data-width=\"225\" data-height=\"300\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2024\/09\/lit-fourgon-black-pearl-florium.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"56177cc\" data-elementor-lightbox-title=\"lit-fourgon-black-pearl-florium\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjkxMTQsInVybCI6Imh0dHBzOlwvXC93d3cuZmxldXJldHRlLWZsb3JpdW0uZnJcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzA5XC9saXQtZm91cmdvbi1ibGFjay1wZWFybC1mbG9yaXVtLnBuZyIsInNsaWRlc2hvdyI6IjU2MTc3Y2MifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2024\/09\/lit-fourgon-black-pearl-florium-300x224.png\" data-width=\"300\" data-height=\"224\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2024\/09\/cuisine-fourgon-black-pearl-florium.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"56177cc\" data-elementor-lightbox-title=\"cuisine-fourgon-black-pearl-florium\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjkxMDksInVybCI6Imh0dHBzOlwvXC93d3cuZmxldXJldHRlLWZsb3JpdW0uZnJcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzA5XC9jdWlzaW5lLWZvdXJnb24tYmxhY2stcGVhcmwtZmxvcml1bS5wbmciLCJzbGlkZXNob3ciOiI1NjE3N2NjIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2024\/09\/cuisine-fourgon-black-pearl-florium-225x300.png\" data-width=\"225\" data-height=\"300\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c3bede6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c3bede6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6d74aa7\" data-id=\"6d74aa7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4e5d00d elementor-widget elementor-widget-spacer\" data-id=\"4e5d00d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Neu: Der Camper Van BLACK PEARL by Florium Die Marke Florium steigt mit ihrem brandneuen Camper Van BLACK PEARL in den Camper-Van-Sektor ein. Zwei Fahrzeuge werden vorab auf der Freizeitfahrzeugmesse in Paris-Villepinte vom 21. bis zum 29. September vorgestellt. Unser Team erwartet Sie im Ausstellungsbereich Fleurette-Florium HALLE 5A, Stand C8! Mit diesem neuen Fahrzeug auf [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":29583,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[41],"tags":[],"class_list":["post-29471","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-unkategorisiert"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Neu: Der Camper Van BLACK PEARL by Florium - Fleurette Florium<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fleurette-florium.fr\/de\/neu-der-camper-van-black-pearl-by-florium\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Neu: Der Camper Van BLACK PEARL by Florium - Fleurette Florium\" \/>\n<meta property=\"og:description\" content=\"Neu: Der Camper Van BLACK PEARL by Florium Die Marke Florium steigt mit ihrem brandneuen Camper Van BLACK PEARL in den Camper-Van-Sektor ein. Zwei Fahrzeuge werden vorab auf der Freizeitfahrzeugmesse in Paris-Villepinte vom 21. bis zum 29. September vorgestellt. Unser Team erwartet Sie im Ausstellungsbereich Fleurette-Florium HALLE 5A, Stand C8! Mit diesem neuen Fahrzeug auf [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fleurette-florium.fr\/de\/neu-der-camper-van-black-pearl-by-florium\/\" \/>\n<meta property=\"og:site_name\" content=\"Fleurette Florium\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-02T08:58:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-02T09:44:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2024\/10\/miniature-black-pearl-actu-florium-NL.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1480\" \/>\n\t<meta property=\"og:image:height\" content=\"1111\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"comwell\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"comwell\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/de\\\/neu-der-camper-van-black-pearl-by-florium\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/de\\\/neu-der-camper-van-black-pearl-by-florium\\\/\"},\"author\":{\"name\":\"comwell\",\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/#\\\/schema\\\/person\\\/adedc337728c96916b930ee17be3c59c\"},\"headline\":\"Neu: Der Camper Van BLACK PEARL by Florium\",\"datePublished\":\"2024-10-02T08:58:59+00:00\",\"dateModified\":\"2024-10-02T09:44:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/de\\\/neu-der-camper-van-black-pearl-by-florium\\\/\"},\"wordCount\":432,\"publisher\":{\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/de\\\/neu-der-camper-van-black-pearl-by-florium\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/miniature-black-pearl-actu-florium-NL.jpg\",\"articleSection\":[\"Unkategorisiert\"],\"inLanguage\":\"de-DE\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/de\\\/neu-der-camper-van-black-pearl-by-florium\\\/\",\"url\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/de\\\/neu-der-camper-van-black-pearl-by-florium\\\/\",\"name\":\"Neu: Der Camper Van BLACK PEARL by Florium - Fleurette Florium\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/de\\\/neu-der-camper-van-black-pearl-by-florium\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/de\\\/neu-der-camper-van-black-pearl-by-florium\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/miniature-black-pearl-actu-florium-NL.jpg\",\"datePublished\":\"2024-10-02T08:58:59+00:00\",\"dateModified\":\"2024-10-02T09:44:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/de\\\/neu-der-camper-van-black-pearl-by-florium\\\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fleurette-florium.fr\\\/de\\\/neu-der-camper-van-black-pearl-by-florium\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/de\\\/neu-der-camper-van-black-pearl-by-florium\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/miniature-black-pearl-actu-florium-NL.jpg\",\"contentUrl\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/miniature-black-pearl-actu-florium-NL.jpg\",\"width\":1480,\"height\":1111},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/de\\\/neu-der-camper-van-black-pearl-by-florium\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\",\"item\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Neu: Der Camper Van BLACK PEARL by Florium\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/#website\",\"url\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/\",\"name\":\"Fleurette Florium\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/#organization\",\"name\":\"Fleurette Florium\",\"url\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/logo-fleurette-florium-scaled.png\",\"contentUrl\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/logo-fleurette-florium-scaled.png\",\"width\":2560,\"height\":830,\"caption\":\"Fleurette Florium\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/#\\\/schema\\\/person\\\/adedc337728c96916b930ee17be3c59c\",\"name\":\"comwell\",\"url\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/de\\\/author\\\/comwell\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Neu: Der Camper Van BLACK PEARL by Florium - Fleurette Florium","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fleurette-florium.fr\/de\/neu-der-camper-van-black-pearl-by-florium\/","og_locale":"de_DE","og_type":"article","og_title":"Neu: Der Camper Van BLACK PEARL by Florium - Fleurette Florium","og_description":"Neu: Der Camper Van BLACK PEARL by Florium Die Marke Florium steigt mit ihrem brandneuen Camper Van BLACK PEARL in den Camper-Van-Sektor ein. Zwei Fahrzeuge werden vorab auf der Freizeitfahrzeugmesse in Paris-Villepinte vom 21. bis zum 29. September vorgestellt. Unser Team erwartet Sie im Ausstellungsbereich Fleurette-Florium HALLE 5A, Stand C8! Mit diesem neuen Fahrzeug auf [&hellip;]","og_url":"https:\/\/www.fleurette-florium.fr\/de\/neu-der-camper-van-black-pearl-by-florium\/","og_site_name":"Fleurette Florium","article_published_time":"2024-10-02T08:58:59+00:00","article_modified_time":"2024-10-02T09:44:28+00:00","og_image":[{"width":1480,"height":1111,"url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2024\/10\/miniature-black-pearl-actu-florium-NL.jpg","type":"image\/jpeg"}],"author":"comwell","twitter_misc":{"Verfasst von":"comwell","Gesch\u00e4tzte Lesezeit":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fleurette-florium.fr\/de\/neu-der-camper-van-black-pearl-by-florium\/#article","isPartOf":{"@id":"https:\/\/www.fleurette-florium.fr\/de\/neu-der-camper-van-black-pearl-by-florium\/"},"author":{"name":"comwell","@id":"https:\/\/www.fleurette-florium.fr\/#\/schema\/person\/adedc337728c96916b930ee17be3c59c"},"headline":"Neu: Der Camper Van BLACK PEARL by Florium","datePublished":"2024-10-02T08:58:59+00:00","dateModified":"2024-10-02T09:44:28+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fleurette-florium.fr\/de\/neu-der-camper-van-black-pearl-by-florium\/"},"wordCount":432,"publisher":{"@id":"https:\/\/www.fleurette-florium.fr\/#organization"},"image":{"@id":"https:\/\/www.fleurette-florium.fr\/de\/neu-der-camper-van-black-pearl-by-florium\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2024\/10\/miniature-black-pearl-actu-florium-NL.jpg","articleSection":["Unkategorisiert"],"inLanguage":"de-DE"},{"@type":"WebPage","@id":"https:\/\/www.fleurette-florium.fr\/de\/neu-der-camper-van-black-pearl-by-florium\/","url":"https:\/\/www.fleurette-florium.fr\/de\/neu-der-camper-van-black-pearl-by-florium\/","name":"Neu: Der Camper Van BLACK PEARL by Florium - Fleurette Florium","isPartOf":{"@id":"https:\/\/www.fleurette-florium.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fleurette-florium.fr\/de\/neu-der-camper-van-black-pearl-by-florium\/#primaryimage"},"image":{"@id":"https:\/\/www.fleurette-florium.fr\/de\/neu-der-camper-van-black-pearl-by-florium\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2024\/10\/miniature-black-pearl-actu-florium-NL.jpg","datePublished":"2024-10-02T08:58:59+00:00","dateModified":"2024-10-02T09:44:28+00:00","breadcrumb":{"@id":"https:\/\/www.fleurette-florium.fr\/de\/neu-der-camper-van-black-pearl-by-florium\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fleurette-florium.fr\/de\/neu-der-camper-van-black-pearl-by-florium\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.fleurette-florium.fr\/de\/neu-der-camper-van-black-pearl-by-florium\/#primaryimage","url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2024\/10\/miniature-black-pearl-actu-florium-NL.jpg","contentUrl":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2024\/10\/miniature-black-pearl-actu-florium-NL.jpg","width":1480,"height":1111},{"@type":"BreadcrumbList","@id":"https:\/\/www.fleurette-florium.fr\/de\/neu-der-camper-van-black-pearl-by-florium\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"","item":"https:\/\/www.fleurette-florium.fr\/de\/"},{"@type":"ListItem","position":2,"name":"Neu: Der Camper Van BLACK PEARL by Florium"}]},{"@type":"WebSite","@id":"https:\/\/www.fleurette-florium.fr\/#website","url":"https:\/\/www.fleurette-florium.fr\/","name":"Fleurette Florium","description":"","publisher":{"@id":"https:\/\/www.fleurette-florium.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fleurette-florium.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/www.fleurette-florium.fr\/#organization","name":"Fleurette Florium","url":"https:\/\/www.fleurette-florium.fr\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.fleurette-florium.fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2021\/07\/logo-fleurette-florium-scaled.png","contentUrl":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2021\/07\/logo-fleurette-florium-scaled.png","width":2560,"height":830,"caption":"Fleurette Florium"},"image":{"@id":"https:\/\/www.fleurette-florium.fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.fleurette-florium.fr\/#\/schema\/person\/adedc337728c96916b930ee17be3c59c","name":"comwell","url":"https:\/\/www.fleurette-florium.fr\/de\/author\/comwell\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fleurette-florium.fr\/de\/wp-json\/wp\/v2\/posts\/29471","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fleurette-florium.fr\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fleurette-florium.fr\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fleurette-florium.fr\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fleurette-florium.fr\/de\/wp-json\/wp\/v2\/comments?post=29471"}],"version-history":[{"count":14,"href":"https:\/\/www.fleurette-florium.fr\/de\/wp-json\/wp\/v2\/posts\/29471\/revisions"}],"predecessor-version":[{"id":29636,"href":"https:\/\/www.fleurette-florium.fr\/de\/wp-json\/wp\/v2\/posts\/29471\/revisions\/29636"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fleurette-florium.fr\/de\/wp-json\/wp\/v2\/media\/29583"}],"wp:attachment":[{"href":"https:\/\/www.fleurette-florium.fr\/de\/wp-json\/wp\/v2\/media?parent=29471"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fleurette-florium.fr\/de\/wp-json\/wp\/v2\/categories?post=29471"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fleurette-florium.fr\/de\/wp-json\/wp\/v2\/tags?post=29471"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}