{"id":25755,"date":"2023-10-23T11:00:27","date_gmt":"2023-10-23T10:00:27","guid":{"rendered":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2023\/10\/Photo-Rugby-4.png"},"modified":"2023-10-23T11:00:52","modified_gmt":"2023-10-23T10:00:52","slug":"photo-rugby-4-2-2","status":"inherit","type":"attachment","link":"https:\/\/www.fleurette-florium.fr\/de\/photo-rugby-4-2-2\/","title":{"rendered":"Photo Rugby 4"},"author":8791,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"media_folder":[],"class_list":["post-25755","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Photo Rugby 4 - Fleurette Florium<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2023\/10\/Photo-Rugby-4.png\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Photo Rugby 4 - Fleurette Florium\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2023\/10\/Photo-Rugby-4.png\" \/>\n<meta property=\"og:site_name\" content=\"Fleurette Florium\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-23T10:00:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2023\/10\/Photo-Rugby-4.png\" \/>\n\t<meta property=\"og:image:width\" content=\"647\" \/>\n\t<meta property=\"og:image:height\" content=\"427\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Photo-Rugby-4.png\",\"url\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Photo-Rugby-4.png\",\"name\":\"Photo Rugby 4 - Fleurette Florium\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/#website\"},\"datePublished\":\"2023-10-23T10:00:27+00:00\",\"dateModified\":\"2023-10-23T10:00:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Photo-Rugby-4.png#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fleurette-florium.fr\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Photo-Rugby-4.png\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Photo-Rugby-4.png#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\",\"item\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Photo Rugby 4\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/#website\",\"url\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/\",\"name\":\"Fleurette Florium\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/#organization\",\"name\":\"Fleurette Florium\",\"url\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/logo-fleurette-florium-scaled.png\",\"contentUrl\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/logo-fleurette-florium-scaled.png\",\"width\":2560,\"height\":830,\"caption\":\"Fleurette Florium\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Photo Rugby 4 - Fleurette Florium","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2023\/10\/Photo-Rugby-4.png","og_locale":"de_DE","og_type":"article","og_title":"Photo Rugby 4 - Fleurette Florium","og_url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2023\/10\/Photo-Rugby-4.png","og_site_name":"Fleurette Florium","article_modified_time":"2023-10-23T10:00:52+00:00","og_image":[{"width":647,"height":427,"url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2023\/10\/Photo-Rugby-4.png","type":"image\/png"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2023\/10\/Photo-Rugby-4.png","url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2023\/10\/Photo-Rugby-4.png","name":"Photo Rugby 4 - Fleurette Florium","isPartOf":{"@id":"https:\/\/www.fleurette-florium.fr\/#website"},"datePublished":"2023-10-23T10:00:27+00:00","dateModified":"2023-10-23T10:00:52+00:00","breadcrumb":{"@id":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2023\/10\/Photo-Rugby-4.png#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2023\/10\/Photo-Rugby-4.png"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2023\/10\/Photo-Rugby-4.png#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"","item":"https:\/\/www.fleurette-florium.fr\/de\/"},{"@type":"ListItem","position":2,"name":"Photo Rugby 4"}]},{"@type":"WebSite","@id":"https:\/\/www.fleurette-florium.fr\/#website","url":"https:\/\/www.fleurette-florium.fr\/","name":"Fleurette Florium","description":"","publisher":{"@id":"https:\/\/www.fleurette-florium.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fleurette-florium.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/www.fleurette-florium.fr\/#organization","name":"Fleurette Florium","url":"https:\/\/www.fleurette-florium.fr\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.fleurette-florium.fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2021\/07\/logo-fleurette-florium-scaled.png","contentUrl":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2021\/07\/logo-fleurette-florium-scaled.png","width":2560,"height":830,"caption":"Fleurette Florium"},"image":{"@id":"https:\/\/www.fleurette-florium.fr\/#\/schema\/logo\/image\/"}}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2023\/10\/Photo-Rugby-4.png'><img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"198\" src=\"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2023\/10\/Photo-Rugby-4-300x198.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2023\/10\/Photo-Rugby-4-300x198.png 300w, https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2023\/10\/Photo-Rugby-4.png 647w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/png","media_details":{"width":647,"height":427,"file":"2023\/10\/Photo-Rugby-4.png","filesize":383697,"sizes":{"medium":{"file":"Photo-Rugby-4-300x198.png","width":300,"height":198,"filesize":89620,"mime_type":"image\/png","source_url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2023\/10\/Photo-Rugby-4-300x198.png"},"thumbnail":{"file":"Photo-Rugby-4-150x150.png","width":150,"height":150,"filesize":36891,"mime_type":"image\/png","source_url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2023\/10\/Photo-Rugby-4-150x150.png"},"cmplz_banner_image":{"file":"Photo-Rugby-4-350x100.png","width":350,"height":100,"filesize":51144,"mime_type":"image\/png","source_url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2023\/10\/Photo-Rugby-4-350x100.png"},"full":{"file":"Photo-Rugby-4.png","width":647,"height":427,"mime_type":"image\/png","source_url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2023\/10\/Photo-Rugby-4.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2023\/10\/Photo-Rugby-4.png","_links":{"self":[{"href":"https:\/\/www.fleurette-florium.fr\/de\/wp-json\/wp\/v2\/media\/25755","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fleurette-florium.fr\/de\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.fleurette-florium.fr\/de\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.fleurette-florium.fr\/de\/wp-json\/wp\/v2\/users\/8791"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fleurette-florium.fr\/de\/wp-json\/wp\/v2\/comments?post=25755"}],"wp:term":[{"taxonomy":"media_folder","embeddable":true,"href":"https:\/\/www.fleurette-florium.fr\/de\/wp-json\/wp\/v2\/media_folder?post=25755"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}