{"id":20904,"date":"2021-11-29T13:56:37","date_gmt":"2021-11-29T12:56:37","guid":{"rendered":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2021\/11\/1.png"},"modified":"2021-11-29T13:56:37","modified_gmt":"2021-11-29T12:56:37","slug":"1-2","status":"inherit","type":"attachment","link":"https:\/\/www.fleurette-florium.fr\/de\/360-ansichtvirtuelle\/1-2\/","title":{"rendered":"1"},"author":6685,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"media_folder":[],"class_list":["post-20904","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>1 - Fleurette Florium<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2021\/11\/1.png\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"1 - Fleurette Florium\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2021\/11\/1.png\" \/>\n<meta property=\"og:site_name\" content=\"Fleurette Florium\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2021\/11\/1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"940\" \/>\n\t<meta property=\"og:image:height\" content=\"788\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/1.png\",\"url\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/1.png\",\"name\":\"1 - Fleurette Florium\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/#website\"},\"datePublished\":\"2021-11-29T12:56:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/1.png#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fleurette-florium.fr\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/1.png\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/1.png#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\",\"item\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"360\u00b0 Ansichtvirtuelle\",\"item\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/de\\\/360-ansichtvirtuelle\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/#website\",\"url\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/\",\"name\":\"Fleurette Florium\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/#organization\",\"name\":\"Fleurette Florium\",\"url\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/logo-fleurette-florium-scaled.png\",\"contentUrl\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/logo-fleurette-florium-scaled.png\",\"width\":2560,\"height\":830,\"caption\":\"Fleurette Florium\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fleurette-florium.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"1 - Fleurette Florium","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2021\/11\/1.png","og_locale":"de_DE","og_type":"article","og_title":"1 - Fleurette Florium","og_url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2021\/11\/1.png","og_site_name":"Fleurette Florium","og_image":[{"width":940,"height":788,"url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2021\/11\/1.png","type":"image\/png"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2021\/11\/1.png","url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2021\/11\/1.png","name":"1 - Fleurette Florium","isPartOf":{"@id":"https:\/\/www.fleurette-florium.fr\/#website"},"datePublished":"2021-11-29T12:56:37+00:00","breadcrumb":{"@id":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2021\/11\/1.png#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2021\/11\/1.png"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2021\/11\/1.png#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"","item":"https:\/\/www.fleurette-florium.fr\/de\/"},{"@type":"ListItem","position":2,"name":"360\u00b0 Ansichtvirtuelle","item":"https:\/\/www.fleurette-florium.fr\/de\/360-ansichtvirtuelle\/"},{"@type":"ListItem","position":3,"name":"1"}]},{"@type":"WebSite","@id":"https:\/\/www.fleurette-florium.fr\/#website","url":"https:\/\/www.fleurette-florium.fr\/","name":"Fleurette Florium","description":"","publisher":{"@id":"https:\/\/www.fleurette-florium.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fleurette-florium.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/www.fleurette-florium.fr\/#organization","name":"Fleurette Florium","url":"https:\/\/www.fleurette-florium.fr\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.fleurette-florium.fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2021\/07\/logo-fleurette-florium-scaled.png","contentUrl":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2021\/07\/logo-fleurette-florium-scaled.png","width":2560,"height":830,"caption":"Fleurette Florium"},"image":{"@id":"https:\/\/www.fleurette-florium.fr\/#\/schema\/logo\/image\/"}}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2021\/11\/1.png'><img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"251\" src=\"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2021\/11\/1-300x251.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2021\/11\/1-300x251.png 300w, https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2021\/11\/1-768x644.png 768w, https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2021\/11\/1.png 940w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/png","media_details":{"width":940,"height":788,"file":"2021\/11\/1.png","sizes":{"medium":{"file":"1-300x251.png","width":300,"height":251,"mime_type":"image\/png","source_url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2021\/11\/1-300x251.png"},"thumbnail":{"file":"1-150x150.png","width":150,"height":150,"mime_type":"image\/png","source_url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2021\/11\/1-150x150.png"},"medium_large":{"file":"1-768x644.png","width":768,"height":644,"mime_type":"image\/png","source_url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2021\/11\/1-768x644.png"},"tp-image-grid":{"file":"1-700x700.png","width":700,"height":700,"mime_type":"image\/png","source_url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2021\/11\/1-700x700.png"},"full":{"file":"1.png","width":940,"height":788,"mime_type":"image\/png","source_url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2021\/11\/1.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":19638,"source_url":"https:\/\/www.fleurette-florium.fr\/wp-content\/uploads\/2021\/11\/1.png","_links":{"self":[{"href":"https:\/\/www.fleurette-florium.fr\/de\/wp-json\/wp\/v2\/media\/20904","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fleurette-florium.fr\/de\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.fleurette-florium.fr\/de\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.fleurette-florium.fr\/de\/wp-json\/wp\/v2\/users\/6685"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fleurette-florium.fr\/de\/wp-json\/wp\/v2\/comments?post=20904"}],"wp:term":[{"taxonomy":"media_folder","embeddable":true,"href":"https:\/\/www.fleurette-florium.fr\/de\/wp-json\/wp\/v2\/media_folder?post=20904"}],"wp:attached-to":[{"embeddable":true,"post_type":"page","id":19638,"href":"https:\/\/www.fleurette-florium.fr\/de\/wp-json\/wp\/v2\/pages\/19638"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}